{"id":20523,"date":"2025-09-02T12:52:38","date_gmt":"2025-09-02T10:52:38","guid":{"rendered":"https:\/\/www.hoenle.com\/produkte-loesungen\/produkt-kategorien\/uvc-water-treatment\/"},"modified":"2026-08-25T10:51:01","modified_gmt":"2026-08-25T08:51:01","slug":"uvc-wasser-desinfektion","status":"publish","type":"page","link":"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/","title":{"rendered":"UV-C Wasserdesinfektionsl\u00f6sungen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section css=&#8221;.vc_custom_1752143461288{background-color: #F2F4F6 !important;}&#8221;][vc_row][vc_column]\n<h1 class=\"akt-heading akt-heading--inline akt-heading--h1 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">UV-C Wasser<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">Desinfektionsl\u00f6sungen<\/span>\n    <\/h1>\n<p class=\"akt-h1-subline akt-h1-subline--align-left\">\n    Wasserqualit\u00e4t sch\u00fctzen. Prozesssicherheit erh\u00f6hen. Mikroorganismen reduzieren.<\/p>[vc_column_text css=&#8221;&#8221;]<\/p>\n<p data-start=\"308\" data-end=\"634\">Ob Trinkwasser, Prozesswasser oder industrielle Wasseranwendungen &#8211; Hoenle bietet zuverl\u00e4ssige UV-C-L\u00f6sungen zur chemiefreien Wasserdesinfektion. Von kompakten Standardanlagen bis hin zu vollst\u00e4ndig kundenspezifischen Systemen unterst\u00fctzen wir Unternehmen dabei, die Wasserqualit\u00e4t zu verbessern, Prozesse sicherer zu gestalten und die Betriebseffizienz zu steigern.<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/5&#8243;]\n<div class=\"akt-button-wrapper akt-button-wrapper--align-left\">\n            <a href=\"https:\/\/www.hoenle.com\/de\/kontakt\/\" \n           class=\"akt-button akt-button--medium akt-button--primary akt-button--light\" title=\"Kontakt\" aria-label=\"Kontakt\"                      >\n            <span class=\"akt-button__text\" data-text=\"Experten kontaktieren\">Experten kontaktieren<\/span>\n        <\/a>\n    <\/div>[\/vc_column][vc_column width=&#8221;1\/5&#8243;]\n<div class=\"akt-button-wrapper akt-button-wrapper--align-left\">\n            <a href=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/Flyer_Water_Disinfection_WEB_DE.pdf\" \n           class=\"akt-button akt-button--medium akt-button--primary akt-button--light\" aria-label=\"Brosch\u00fcre downloaden\"                      >\n            <span class=\"akt-button__text\" data-text=\"Brosch\u00fcre downloaden\">Brosch\u00fcre downloaden<\/span>\n        <\/a>\n    <\/div>[vc_empty_space][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1756033442353{background-color: #FFFFFF !important;}&#8221;][vc_row][vc_column][vc_empty_space]\n<h2 class=\"akt-heading akt-heading--inline akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Finden Sie die<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">richtige L\u00f6sung<\/span>\n    <\/h2>[vc_column_text css=&#8221;&#8221;]<\/p>\n<p data-start=\"313\" data-end=\"504\">Jeder Wasseraufbereitungsprozess stellt individuelle Anforderungen an die Desinfektion. Ob kompakte Standardl\u00f6sung, integrierte OEM-L\u00f6sung oder vollst\u00e4ndig kundenspezifisches System &#8211; Hoenle bietet UV-C-L\u00f6sungen f\u00fcr eine zuverl\u00e4ssige und effiziente Wasserdesinfektion.<\/p>\n<p>[\/vc_column_text][vc_tta_tabs][vc_tta_section title=&#8221;Systeme&#8221; tab_id=&#8221;systeme&#8221;]\n<div class=\"akt-grid akt-grid--columns-4 akt-grid--align-center akt-grid--aspect-4_3 akt-grid--hover akt-grid--fit-contain akt-grid--animation-fade_in\" \n     id=\"akt-grid-6a980ab4311ec\"\n     data-columns=\"4\"\n     data-animation=\"fade-in\">\n\n            <style>@media (max-width: 768px) { #akt-grid-6a980ab4311ec .akt-grid__content { background-color: #ffffff; } }<\/style>\n         \n    \n            <div class=\"akt-grid__container\">\n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"0\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/asuv-serie\/\"\n                                                                                     title=\"ASUV-Serie\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--4_3\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/A1250-Aquastera-scaled-scaled-e1765889369673.png\" \n                                 alt=\"ASUV-Serie\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"940\"\n                                 height=\"940\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">ASUV-Serie<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Zertifizierte Wasserdesinfektions-Anlagen<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"1\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/wds-serie\/\"\n                                                                                     title=\"WDS-Serie\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--4_3\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/WDS1-scaled-scaled-e1765801572276.png\" \n                                 alt=\"WDS-Serie\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"1084\"\n                                 height=\"1024\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">WDS-Serie<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Wasserdesinfektionsanlagen f\u00fcr den privaten Gebrauch<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"2\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/tl-ts-serie\/\"\n                                                                                     title=\"TS-Serie\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--4_3\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/TSBox-e1766486760505.png\" \n                                 alt=\"TS-Serie\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"1300\"\n                                 height=\"1300\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">TS-Serie<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Tauchlampe inkl. elektronischem Schaltschrank<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"3\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/toc-reaktoren\/\"\n                                                                                     title=\"TOC Reaktoren\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--4_3\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/ABOX-scaled-e1772715095961.png\" \n                                 alt=\"TOC-Reaktoren\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"1027\"\n                                 height=\"1027\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">TOC-Reaktoren<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Reinstwasser Reaktoren<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                    <\/div>\n        \n<\/div>[\/vc_tta_section][vc_tta_section title=&#8221;Komponenten&#8221; tab_id=&#8221;komponenten&#8221;]\n<div class=\"akt-grid akt-grid--columns-4 akt-grid--align-center akt-grid--aspect-4_3 akt-grid--hover akt-grid--fit-cover akt-grid--animation-fade_in\" \n     id=\"akt-grid-6a980ab431b92\"\n     data-columns=\"4\"\n     data-animation=\"fade-in\">\n\n            <style>@media (max-width: 768px) { #akt-grid-6a980ab431b92 .akt-grid__content { background-color: #ffffff; } }<\/style>\n         \n    \n            <div class=\"akt-grid__container\">\n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"0\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/tl-ts-serie\/\"\n                                                                                     title=\"TL\/TS-Serie\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--4_3\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/TL-System-e1765880713960.png\" \n                                 alt=\"TL-Serie\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"530\"\n                                 height=\"410\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">TL-Serie<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Tauchlampe exkl. elektronischem Schaltschrank<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"1\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/produkt-kategorien\/uv-komponenten\/\"\n                                                                                     title=\"UV-Lampen &amp; Komponenten\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--4_3\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/UV-Lamps-Components.png\" \n                                 alt=\"UV-Lampen &amp; Komponenten\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"1203\"\n                                 height=\"994\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">UV-Lampen &amp; Komponenten<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Lampen, elektronische Netzteile, Messger\u00e4te und mehr<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                    <\/div>\n        \n<\/div>[\/vc_tta_section][\/vc_tta_tabs][vc_empty_space][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1787303823427{background-color: #F2F4F6 !important;}&#8221;][vc_row][vc_column][vc_empty_space]\n<h2 class=\"akt-heading akt-heading--inline akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Ihre<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">Vorteile<\/span>\n    <\/h2>[vc_empty_space][vc_column_text css=&#8221;&#8221;]<\/p>\n<p data-start=\"313\" data-end=\"504\">Eine zuverl\u00e4ssige Wasserqualit\u00e4t ist in zahlreichen industriellen, gewerblichen und kommunalen Anwendungen entscheidend. Unsere UV-C-L\u00f6sungen zur Wasserdesinfektion reduzieren Mikroorganismen effektiv &#8211; ganz ohne Chemikalien. Gleichzeitig lassen sie sich flexibel an Ihre spezifischen Prozessanforderungen anpassen und unterst\u00fctzen eine effiziente und nachhaltige Wasseraufbereitung.<\/p>\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;26576&#8243; alignment=&#8221;center&#8221; css=&#8221;&#8221; title=&#8221;Chemiefrei&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;26470&#8243; alignment=&#8221;center&#8221; css=&#8221;&#8221; title=&#8221;Wartungsarm&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_single_image image=&#8221;26504&#8243; alignment=&#8221;center&#8221; css=&#8221;&#8221; title=&#8221;Individuelle L\u00f6sungen&#8221;][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1787303828463{background-color: #FFFFFF !important;}&#8221;][vc_row][vc_column][vc_empty_space]\n<h2 class=\"akt-heading akt-heading--inline akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Typische Anwendungen<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">von UV-C Wasserdesinfektion<\/span>\n    <\/h2>[vc_empty_space][vc_column_text css=&#8221;&#8221;]Unsere UV-C-L\u00f6sungen zur Wasserdesinfektion kommen in zahlreichen Branchen und unterschiedlichen Wasseraufbereitungsanwendungen zum Einsatz. Die folgenden Beispiele zeigen einige der h\u00e4ufigsten Einsatzbereiche unserer Technologie.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/5&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li>Trinkwasser<\/li>\n<li>Prozesswasser<\/li>\n<li>Industriewasser<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li>K\u00fchlwasser<\/li>\n<li>Abwasser<\/li>\n<li>Lebensmittelindustrie<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][vc_column_text css=&#8221;&#8221;]<\/p>\n<ul>\n<li>Pharmawasser<\/li>\n<li>Teiche<\/li>\n<li>&#8230; und mehr<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row][\/vc_section][vc_section disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1783504115773{background-color: #FFFFFF !important;}&#8221;][vc_row][vc_column]\n<h2 class=\"akt-heading akt-heading--inline akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Komplette<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">Wasserdesinfektions-Systeme<\/span>\n    <\/h2>[vc_column_text css=&#8221;&#8221;]<\/p>\n<p data-start=\"313\" data-end=\"504\">UVC-Wasserreaktoren bieten zuverl\u00e4ssige Desinfektion f\u00fcr ein breites Anwendungsspektrum \u2013 von Privathaushalten \u00fcber industrielle Prozesse bis hin zur Abwasserbehandlung.<\/p>\n<p data-start=\"506\" data-end=\"752\">Die Reaktoren eliminieren effizient Mikroorganismen \u2013 ohne chemische Zus\u00e4tze. Durch hohe Leistung und flexible Einsatzm\u00f6glichkeiten k\u00f6nnen sie als eigenst\u00e4ndige Systeme betrieben oder in bestehende Anlagen integriert werden.<\/p>\n<p data-start=\"754\" data-end=\"949\">So wird hygienisch sicheres Wasser in unterschiedlichsten Umgebungen gew\u00e4hrleistet, und konstante Wasserqualit\u00e4t sichergestellt, wo immer zuverl\u00e4ssige Desinfektion erforderlich ist.<\/p>\n<p>[\/vc_column_text]\n<div class=\"akt-grid akt-grid--columns-4 akt-grid--align-center akt-grid--aspect-1_1 akt-grid--hover akt-grid--fit-cover akt-grid--animation-fade_in\" \n     id=\"akt-grid-6a980ab432145\"\n     data-columns=\"4\"\n     data-animation=\"fade-in\">\n\n            <style>@media (max-width: 768px) { #akt-grid-6a980ab432145 .akt-grid__content { background-color: #ffffff; } }<\/style>\n         \n    \n            <div class=\"akt-grid__container\">\n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"0\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/reinstwasser\/\"\n                                                                                     title=\"TOC-Reaktoren\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--1_1\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/ABOX-scaled-e1772715095961.png\" \n                                 alt=\"TOC-Reaktoren\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"1027\"\n                                 height=\"1027\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">TOC-Reaktoren<\/h3>\n                                                        \n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"1\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/asuv-serie\/\"\n                                                                                     title=\"ASUV-Serie\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--1_1\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/A1250-Aquastera-scaled-scaled-e1765889369673.png\" \n                                 alt=\"ASUV-Serie\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"940\"\n                                 height=\"940\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">ASUV-Serie<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Zertifizierte Wasserdesinfektions-Anlagen<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"2\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/wds-serie\/\"\n                                                                                     title=\"WDS-Serie\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--1_1\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/WDS1-scaled-scaled-e1765801572276.png\" \n                                 alt=\"WDS-Serie\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"1084\"\n                                 height=\"1024\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">WDS-Serie<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Wasserdesinfektionsanlagen f\u00fcr den privaten Gebrauch<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"3\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/produkt-kategorien\/uvc-wasser-desinfektion\/tl-ts-serie\/\"\n                                                                                     title=\"TS-Serie\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--1_1\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/TSBox-e1766486760505.png\" \n                                 alt=\"TS-Serie\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"1300\"\n                                 height=\"1300\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">TS-Serie<\/h3>\n                                                        \n                                                            <p class=\"akt-grid__description\">Tauchlampe inkl. elektronischem Schaltschrank<\/p>\n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                    <\/div>\n        \n<\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1783504629989{background-color: #F2F4F6 !important;}&#8221;][vc_row][vc_column]\n<h2 class=\"akt-heading akt-heading--inline akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Haben Sie<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">Fragen?<\/span>\n    <\/h2>[\/vc_column][\/vc_row][vc_row][vc_column][vc_toggle title=&#8221;Was genau ist UV-C Wasserdesinfektion?&#8221; style=&#8221;simple&#8221; color=&#8221;sky&#8221; css=&#8221;&#8221;]UVC-Strahlung ist eine bew\u00e4hrte und hochwirksame Methode zur Inaktivierung von Bakterien und Viren in Fl\u00fcssigkeiten. Sie wird h\u00e4ufig zur Desinfektion von Trinkwasser, Prozesswasser, Aquakultursystemen, Pools und Whirlpools, Brunnen, Filtersystemen, medizinischen Instrumenten und vielem mehr eingesetzt.<br \/>\nSauberes Wasser ist eine der wertvollsten Ressourcen der Erde. Mit Hilfe der UVC-Desinfektion kann kontaminiertes Wasser mit einer Wirksamkeit von bis zu 99,99 % behandelt werden. Es stehen verschiedene Ger\u00e4te f\u00fcr unterschiedliche Anwendungen zur Verf\u00fcgung. Es wird empfohlen, sich von Experten beraten zu lassen, um die richtige L\u00f6sung f\u00fcr eine sichere und effiziente Wasserdesinfektion zu finden.[\/vc_toggle][vc_toggle title=&#8221;In welchen Bereichen wird die UVC-Wasserdesinfektion eingesetzt?&#8221; style=&#8221;simple&#8221; color=&#8221;sky&#8221; css=&#8221;&#8221;]Die UV-Wasserdesinfektion ist ideal, wenn chemische Desinfektionsmittel sch\u00e4dliche Auswirkungen haben k\u00f6nnen oder wenn hohe Temperaturen f\u00fcr die Aufbereitung von (Trink-)Wasser ungeeignet sind.<\/p>\n<p>H\u00e4ufige Anwendungsbereiche sind:<\/p>\n<ul>\n<li>Ballastwassersysteme<\/li>\n<li>Reinstwasser f\u00fcr die Halbleiterindustrie<\/li>\n<li>Kommunale und private Trinkwasserversorgung<\/li>\n<li>Aquakultur und Gartenbau<\/li>\n<li>\u00d6ffentliche Schwimmb\u00e4der und Schwimmb\u00e4der<\/li>\n<li>Gartenteiche und Brunnen<\/li>\n<li>Lebensmittel- und Getr\u00e4nkeindustrie<\/li>\n<li>Pharmazeutische und kosmetische Industrie<\/li>\n<li>Badewasseraufbereitung<\/li>\n<li>Wasseranalyse (TN, TP, TOC)<\/li>\n<\/ul>\n<p>[\/vc_toggle][vc_toggle title=&#8221;Wie funktioniert UV-C Wasserdesinfektion?&#8221; style=&#8221;simple&#8221; color=&#8221;sky&#8221; css=&#8221;&#8221;]Die Einrichtung h\u00e4ngt von der beabsichtigten Anwendung ab. Im Allgemeinen werden UV-Lampen in einem Wasserdesinfektionssystem installiert, das kurzwelliges ultraviolettes Licht mit einer Wellenl\u00e4nge von 253,7 nm emittiert.<br \/>\nDiese UVC-Sterilisatoren sind in den Filterkreislauf integriert, sodass das Wasser an der UV-Lampe vorbeiflie\u00dfen kann. Die intensive Strahlung inaktiviert Keime wirksam und macht das Wasser sicher, ohne seine Qualit\u00e4t zu beeintr\u00e4chtigen \u2013 v\u00f6llig ohne Chemikalien.<br \/>\nF\u00fcr eine zuverl\u00e4ssige Desinfektion ist eine bestimmte Strahlungsintensit\u00e4t erforderlich, um sicherzustellen, dass alle Mikroorganismen wirksam deaktiviert werden. Diese Intensit\u00e4t muss f\u00fcr jede Anwendung genau berechnet werden.[\/vc_toggle][vc_toggle title=&#8221;Welche Ger\u00e4te werden f\u00fcr die UVC-Wasserdesinfektion verwendet?&#8221; style=&#8221;simple&#8221; color=&#8221;sky&#8221; css=&#8221;&#8221;]F\u00fcr eine Vielzahl von Anwendungen stehen verschiedene UV-Wasserdesinfektionsger\u00e4te zur Verf\u00fcgung. F\u00fcr Privathaushalte oder den industriellen Einsatz sind <b>Durchflusssysteme<\/b> ideal, da sie nur eine kurze Kontaktzeit ben\u00f6tigen, um Mikroorganismen zu inaktivieren.<\/p>\n<p>In K\u00fchlt\u00fcrmen, Luftw\u00e4schern oder Wassertanks werden h\u00e4ufig <b>austauschbare UVC-Lampen<\/b> verwendet. <b>UV-Tauchlampen<\/b>, auch UV-Kl\u00e4rer genannt, werden vollst\u00e4ndig unter Wasser getaucht und oft durch eine Quarzglasr\u00f6hre gesch\u00fctzt, um eine maximale Effizienz zu erzielen.<\/p>\n<p>In Aquarien verf\u00fcgen <b>UV-Filter<\/b> \u00fcber eine mit UV-Strahlung beleuchtete Kammer, die in der Regel in den Wasserkreislauf eines Au\u00dfenfilters integriert oder \u00fcber ein Bypass-System angeschlossen ist. Diese L\u00f6sungen gew\u00e4hrleisten eine effektive, chemikalienfreie Wasserdesinfektion in einer Vielzahl von Umgebungen.[\/vc_toggle][vc_toggle title=&#8221;Welche Wirkung hat die UVC-Wasserdesinfektion auf Krankheitserreger?&#8221; style=&#8221;simple&#8221; color=&#8221;sky&#8221; css=&#8221;&#8221;]Ein UV-System erm\u00f6glicht eine effektive Wasseraufbereitung <b>ohne zus\u00e4tzliche chemische Pflegeprodukte<\/b> und bewahrt gleichzeitig die Wasserqualit\u00e4t vollst\u00e4ndig. Die UV-Desinfektion reduziert auch den messbaren Chloramingehalt im Badewasser und beugt so Haut- und Augenreizungen vor.<\/p>\n<p>Schlie\u00dflich k\u00f6nnen lebende Mikroorganismen wie E. coli, Salmonellen und <i>Cryptosporidium<\/i> keine Resistenz gegen UV-Strahlen entwickeln \u2013 so wird sichergestellt, dass sie zuverl\u00e4ssig abget\u00f6tet werden.[\/vc_toggle][vc_toggle title=&#8221;Was sind die Hauptvorteile der UV-Wasserdesinfektion?&#8221; style=&#8221;simple&#8221; color=&#8221;sky&#8221; css=&#8221;&#8221;]Hier sind einige Vorteile der Verwendung mit UVC-Wasserdesinfektion:<\/p>\n<ul>\n<li>Verwendung ohne Chemikalien<\/li>\n<li>Wirksam gegen eine Vielzahl von Mikroorganismen<\/li>\n<li>Keine Bildung sch\u00e4dlicher Nebenprodukte wie Chlordioxid und Trihalogenmethane<\/li>\n<li>Einfache Bedienung und Wartung<\/li>\n<li>M\u00f6glichkeit der nachhaltigen Nutzung durch erneuerbare Energien wie Solarenergie<\/li>\n<\/ul>\n<p>[\/vc_toggle][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1769527002804{background-color: #FFFFFF !important;}&#8221;][vc_row][vc_column]\n<h2 class=\"akt-heading akt-heading--inline akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Typische Einsatzbereiche<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">in der Wasserdesinfektion<\/span>\n    <\/h2>\n<!-- Custom CSS -->\n<style>#akt-use-cases-slider-1 .akt-use-cases-slider__container { height: 500px; }\n#akt-use-cases-slider-1 .akt-use-cases-slider__slide { height: 500px; }\n@media (max-width: 768px) {\n  #akt-use-cases-slider-1 .akt-use-cases-slider__container { height: 400px; }\n  #akt-use-cases-slider-1 .akt-use-cases-slider__slide { height: 400px; }\n}\n<\/style>\n\n<section class=\"akt-use-cases-slider akt-use-cases-slider--split\" \n         id=\"akt-use-cases-slider-1\"\n                  data-transition-type=\"fade\"\n                  data-auto-play=\"true\"\n                  data-auto-play-speed=\"5000\"\n                  data-transition-duration=\"800\"\n                  data-pause-on-hover=\"true\"\n         >\n\n    <!-- Slider Container (ohne Section Header) -->\n    <div class=\"akt-use-cases-slider__container\" role=\"region\" aria-label=\"Use cases slider\">\n        \n        <!-- Slides -->\n        <div class=\"akt-use-cases-slider__slides\">\n                            <div class=\"akt-use-cases-slider__slide akt-use-cases-slider__slide--left akt-use-cases-slider__slide--align-center akt-use-cases-slider__slide--active\"\n                     data-slide-index=\"0\"\n                     role=\"tabpanel\"\n                     aria-hidden=\"false\"\n                     aria-labelledby=\"slide-tab-akt-use-cases-slider-1-0\">\n                    \n                    <!-- Background Image -->\n                                                                    <div class=\"akt-use-cases-slider__background\"\n                             style=\"background-image: url(&#039;https:\/\/www.hoenle.com\/wp-content\/uploads\/Semiconductor-Header.png&#039;); --akt-bg-ratio: 2560 \/ 1267;\"\n                             role=\"img\"\n                             aria-label=\"UV-Desinfektion f\u00fcr Reinstwasser\">\n                        <\/div>\n                                        \n                    <!-- Background Overlay -->\n                                            <div class=\"akt-use-cases-slider__overlay akt-use-cases-slider__overlay--medium\"><\/div>\n                                        \n                    <!-- Content -->\n                    <div class=\"akt-use-cases-slider__content\">\n                        <div class=\"akt-use-cases-slider__content-inner\">\n                            \n                                                            <h3 class=\"akt-use-cases-slider__slide-title\">\n                                    UV-Desinfektion f\u00fcr Reinstwasser                                <\/h3>\n                                                        \n                                                            <p class=\"akt-use-cases-slider__slide-description\">\n                                    Zuverl\u00e4ssige Leistung ohne Chemikalien                                <\/p>\n                                                        \n                                                            <div class=\"akt-use-cases-slider__slide-actions\">\n                                    <a href=\"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/case-studies\/uv-desinfektion-halbleiter\/\"\n                                       class=\"akt-use-cases-slider__button akt-use-cases-slider__button--primary\"\n                                                                                                                     title=\"UV-Desinfektionssystem in der Halbleiter-Wasseraufbereitung\"\n                                                                              >\n                                        \n                                        <span class=\"akt-use-cases-slider__button-text\">\n                                            Mehr erfahren                                        <\/span>\n                                    <\/a>\n                                <\/div>\n                                                        \n                        <\/div>\n                    <\/div>\n                <\/div>\n                    <\/div>\n\n        <!-- Arrow Navigation (always visible) -->\n        <div class=\"akt-use-cases-slider__arrows\">\n            <button type=\"button\" \n                    class=\"akt-use-cases-slider__arrow akt-use-cases-slider__arrow--prev\"\n                    aria-label=\"Previous slide\"\n                    disabled>\n                <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M15 18L9 12L15 6\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                <\/svg>\n            <\/button>\n            \n            <button type=\"button\" \n                    class=\"akt-use-cases-slider__arrow akt-use-cases-slider__arrow--next\"\n                    aria-label=\"Next slide\">\n                <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M9 18L15 12L9 6\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                <\/svg>\n            <\/button>\n        <\/div>\n\n    <\/div> <!-- End slider container -->\n\n    <!-- Navigation Progress Bar -->\n    \n    <!-- Single slide: full width bar -->\n            <div class=\"akt-use-cases-slider__navigation\" role=\"tablist\" aria-label=\"Slide navigation\">\n            <div class=\"akt-use-cases-slider__progress-segment akt-use-cases-slider__progress-segment--active akt-use-cases-slider__progress-segment--single\"><\/div>\n        <\/div>\n    \n    <!-- Progress Bar (Optional) -->\n    <div class=\"akt-use-cases-slider__progress\" aria-hidden=\"true\">\n        <div class=\"akt-use-cases-slider__progress-bar\"><\/div>\n    <\/div>\n\n    <!-- Loading Indicator -->\n    <div class=\"akt-use-cases-slider__loading\" aria-hidden=\"true\" style=\"display: none;\">\n        <div class=\"akt-use-cases-slider__loading-spinner\">\n            <svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <circle cx=\"12\" cy=\"12\" r=\"10\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-dasharray=\"31.416\" stroke-dashoffset=\"31.416\">\n                    <animate attributeName=\"stroke-dasharray\" dur=\"2s\" values=\"0 31.416;15.708 15.708;0 31.416\" repeatCount=\"indefinite\"\/>\n                    <animate attributeName=\"stroke-dashoffset\" dur=\"2s\" values=\"0;-15.708;-31.416\" repeatCount=\"indefinite\"\/>\n                <\/circle>\n            <\/svg>\n        <\/div>\n    <\/div>\n\n<\/section>\n\n<!-- Accessibility: Screen reader announcements -->\n<div class=\"akt-use-cases-slider__sr-only\" aria-live=\"polite\" aria-atomic=\"true\">\n    <!-- Dynamic content for screen readers will be inserted here by JavaScript -->\n<\/div>\n[\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1757515286039{background-color: #F2F4F6 !important;}&#8221;][vc_row][vc_column width=&#8221;1\/3&#8243;]\n<h2 class=\"akt-heading akt-heading--block akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Kontakt<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">&amp; Support<\/span>\n    <\/h2>[vc_empty_space height=&#8221;15px&#8221;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1783504657425{background-color: #F2F4F6 !important;}&#8221;]Bereit, die richtige UV-C Wasserdesinfektionsl\u00f6sung zu finden?[\/vc_column_text][vc_empty_space height=&#8221;15px&#8221;]\n<div class=\"akt-button-wrapper akt-button-wrapper--align-left\">\n            <a href=\"\/de\/kontakt\" \n           class=\"akt-button akt-button--medium akt-button--primary akt-button--light\" aria-label=\"Support anfragen\"                      >\n            <span class=\"akt-button__text\" data-text=\"Support anfragen\">Support anfragen<\/span>\n        <\/a>\n    <\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1783504666565{background-color: #FFFFFF !important;}&#8221;][vc_row][vc_column]\n<h2 class=\"akt-heading akt-heading--inline akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Finden Sie Ihre<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">Industrie<\/span>\n    <\/h2>\n<div class=\"akt-grid akt-grid--columns-3 akt-grid--align-center akt-grid--aspect-16_9 akt-grid--hover akt-grid--fit-cover akt-grid--animation-fade_in\" \n     id=\"akt-grid-6a980ab4325d6\"\n     data-columns=\"3\"\n     data-animation=\"fade-in\">\n\n            <style>@media (max-width: 768px) { #akt-grid-6a980ab4325d6 .akt-grid__content { background-color: #ffffff; } }<\/style>\n         \n    \n            <div class=\"akt-grid__container\">\n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"0\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/industrien\/food\/lebensmittel\/\"\n                                                                                     title=\"Lebensmittelindustrie\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--16_9\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/Food-Production-Header.png\" \n                                 alt=\"Lebensmittelindustrie\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"2000\"\n                                 height=\"1335\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">Lebensmittelindustrie<\/h3>\n                                                        \n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"1\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"\/de\/produkte-loesungen\/industrien\/health-medical-technology-pharma\/gesundheitswesen\/\"\n                                                                                     title=\"Gesundheitswesen\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--16_9\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/Health-Care.png\" \n                                 alt=\"Gesundheitswesen\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"2000\"\n                                 height=\"874\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">Gesundheitswesen<\/h3>\n                                                        \n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                            \n                <div class=\"akt-grid__item\" \n                     data-index=\"2\"\n                     style=\"--animation-delay: 0s\">\n                    \n                                            <a href=\"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/industrien\/halbleiter\/\"\n                                                                                     title=\"Halbleiter\"\n                                                      class=\"akt-grid__item-link\">\n                                        \n                                            <div class=\"akt-grid__image akt-grid__image--16_9\">\n                            <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/Semiconductor-Industry.png\" \n                                 alt=\"Halbleiter\" \n                                 class=\"akt-grid__image-element\"\n                                 loading=\"lazy\"\n                                 width=\"2000\"\n                                 height=\"1256\">\n                        <\/div>\n                                        \n                                            <div class=\"akt-grid__content\">\n                                                            <h3 class=\"akt-grid__title\">Halbleiter<\/h3>\n                                                        \n                                                    <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                    <\/div>\n        \n<\/div>[\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1783504781472{background-color: #F2F4F6 !important;}&#8221;][vc_row][vc_column]\n<h2 class=\"akt-heading akt-heading--inline akt-heading--h2 akt-heading--align-left\">\n            <span class=\"akt-heading__part akt-heading__part--light\">Suchen Sie nach<\/span>\n                <span class=\"akt-heading__part akt-heading__part--bold\">einer anderen Anwendung?<\/span>\n    <\/h2>\n<div class=\"akt-image-grid-wrapper\">\n    \n            <div class=\"akt-image-grid akt-image-grid--columns-4 akt-image-grid--align-center\">\n                                            \n                <div class=\"akt-image-grid__item akt-image-grid__item--image\" \n                     data-item-index=\"0\"\n                     data-item-id=\"akt-item-0-9439\"\n                     >\n                    \n                                            <a href=\"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/produkt-kategorien\/uvc-luftdesinfektion\/\" \n                           class=\"akt-image-grid__link\"\n                                                      title=\"Luftdesinfektionsl\u00f6sungen\">\n                                        \n                    <div class=\"akt-image-grid__image-container\">\n                                                                                                                    <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/hoenle-icon-luftdesinfektion-typoblau-rgb.svg\" \n                                     alt=\"Luftedesinfektionsl\u00f6sungen\" \n                                     class=\"akt-image-grid__image\"\n                                     style=\"width: 150px; height: 150px;\" \/>\n                                                                        <\/div>\n                    \n                                            <div class=\"akt-image-grid__text\">\n                            Luftedesinfektionsl\u00f6sungen                        <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                \n                                            \n                <div class=\"akt-image-grid__item akt-image-grid__item--image\" \n                     data-item-index=\"1\"\n                     data-item-id=\"akt-item-1-7671\"\n                     >\n                    \n                                            <a href=\"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/produkt-kategorien\/uvc-oberflaechendesinfektion\/\" \n                           class=\"akt-image-grid__link\"\n                                                      title=\"Oberfl\u00e4chendesinfektionsl\u00f6sungen\">\n                                        \n                    <div class=\"akt-image-grid__image-container\">\n                                                                                                                    <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/hoenle-icon-oberflaechendesinfektion-typoblau-rgb.svg\" \n                                     alt=\"Oberfl\u00e4chendesinfektionsl\u00f6sungen\" \n                                     class=\"akt-image-grid__image\"\n                                     style=\"width: 150px; height: 150px;\" \/>\n                                                                        <\/div>\n                    \n                                            <div class=\"akt-image-grid__text\">\n                            Oberfl\u00e4chendesinfektionsl\u00f6sungen                        <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                \n                                            \n                <div class=\"akt-image-grid__item akt-image-grid__item--image\" \n                     data-item-index=\"2\"\n                     data-item-id=\"akt-item-2-3325\"\n                     >\n                    \n                                            <a href=\"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/produkt-kategorien\/uv-komponenten\/\" \n                           class=\"akt-image-grid__link\"\n                                                      title=\"UV-Lampen &amp; Komponenten\">\n                                        \n                    <div class=\"akt-image-grid__image-container\">\n                                                                                                                    <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/hoenle-icon-komponenten-2-typoblau-rgb.svg\" \n                                     alt=\"UV-Lampen &amp; Komponenten\" \n                                     class=\"akt-image-grid__image\"\n                                     style=\"width: 150px; height: 150px;\" \/>\n                                                                        <\/div>\n                    \n                                            <div class=\"akt-image-grid__text\">\n                            UV-Lampen &amp; Komponenten                        <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                \n                                            \n                <div class=\"akt-image-grid__item akt-image-grid__item--image\" \n                     data-item-index=\"3\"\n                     data-item-id=\"akt-item-3-4983\"\n                     >\n                    \n                                            <a href=\"https:\/\/www.hoenle.com\/de\/produkte-loesungen\/anwendungen\/uv-entkeimung\/labor\/\" \n                           class=\"akt-image-grid__link\"\n                                                      title=\"Mikrobiologisches Labor\">\n                                        \n                    <div class=\"akt-image-grid__image-container\">\n                                                                                                                    <img decoding=\"async\" src=\"https:\/\/www.hoenle.com\/wp-content\/uploads\/hoenle-icon-labor-typoblau-rgb.svg\" \n                                     alt=\"Mikrobiologisches Labor\" \n                                     class=\"akt-image-grid__image\"\n                                     style=\"width: 150px; height: 150px;\" \/>\n                                                                        <\/div>\n                    \n                                            <div class=\"akt-image-grid__text\">\n                            Mikrobiologisches Labor                        <\/div>\n                                        \n                                            <\/a>\n                                    <\/div>\n                \n                                \n                    <\/div>\n        \n                \n    <\/div>[\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section css=&#8221;.vc_custom_1752143461288{background-color: #F2F4F6 !important;}&#8221;][vc_row][vc_column][vc_column_text css=&#8221;&#8221;] Ob Trinkwasser, Prozesswasser oder industrielle Wasseranwendungen &#8211; Hoenle bietet zuverl\u00e4ssige UV-C-L\u00f6sungen zur chemiefreien Wasserdesinfektion. Von [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":7256,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"plain-container","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-20523","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/pages\/20523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/comments?post=20523"}],"version-history":[{"count":23,"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/pages\/20523\/revisions"}],"predecessor-version":[{"id":32154,"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/pages\/20523\/revisions\/32154"}],"up":[{"embeddable":true,"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/pages\/7256"}],"wp:attachment":[{"href":"https:\/\/www.hoenle.com\/de\/wp-json\/wp\/v2\/media?parent=20523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}